{"id":8,"count":589,"description":"Travel &amp; Tourism","link":"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/","name":"Travel &amp; Tourism","slug":"travel-tourism","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Travel &amp; Tourism Archives - Live Kerala<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel &amp; Tourism Archives - Live Kerala\" \/>\n<meta property=\"og:description\" content=\"Travel &amp; Tourism\" \/>\n<meta property=\"og:url\" content=\"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Kerala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/\",\"url\":\"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/\",\"name\":\"Travel &amp; Tourism Archives - Live Kerala\",\"isPartOf\":{\"@id\":\"https:\/\/livekerala.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/livekerala.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travel &amp; Tourism\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/livekerala.com\/blog\/#website\",\"url\":\"https:\/\/livekerala.com\/blog\/\",\"name\":\"Live Kerala\",\"description\":\"Free Business Online Directory\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/livekerala.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travel &amp; Tourism Archives - Live Kerala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/","og_locale":"en_US","og_type":"article","og_title":"Travel &amp; Tourism Archives - Live Kerala","og_description":"Travel &amp; Tourism","og_url":"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/","og_site_name":"Live Kerala","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/","url":"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/","name":"Travel &amp; Tourism Archives - Live Kerala","isPartOf":{"@id":"https:\/\/livekerala.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/livekerala.com\/blog\/category\/travel-tourism\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/livekerala.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Travel &amp; Tourism"}]},{"@type":"WebSite","@id":"https:\/\/livekerala.com\/blog\/#website","url":"https:\/\/livekerala.com\/blog\/","name":"Live Kerala","description":"Free Business Online Directory","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/livekerala.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/livekerala.com\/blog\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livekerala.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/livekerala.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/livekerala.com\/blog\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}